{"id":47,"count":39,"description":"","link":"https:\/\/www.lelo.com\/blog\/tag\/holidays\/","name":"Holidays","slug":"holidays","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Holidays Archives - Volont\u00e9<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Holidays Archives - Volont\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lelo.com\/blog\/tag\/holidays\/\" \/>\n<meta property=\"og:site_name\" content=\"Volont\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lelo_Official\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.lelo.com\/blog\/tag\/holidays\/\",\"url\":\"https:\/\/www.lelo.com\/blog\/tag\/holidays\/\",\"name\":\"Holidays Archives - Volont\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/www.lelo.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.lelo.com\/blog\/tag\/holidays\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lelo.com\/blog\/tag\/holidays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Volonte\",\"item\":\"https:\/\/www.lelo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Holidays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lelo.com\/blog\/#website\",\"url\":\"https:\/\/www.lelo.com\/blog\/\",\"name\":\"Volont\u00e9\",\"description\":\"A Sexual Pleasure Blog by LELO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lelo.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Holidays Archives - Volont\u00e9","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Holidays Archives - Volont\u00e9","og_url":"https:\/\/www.lelo.com\/blog\/tag\/holidays\/","og_site_name":"Volont\u00e9","twitter_card":"summary_large_image","twitter_site":"@Lelo_Official","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lelo.com\/blog\/tag\/holidays\/","url":"https:\/\/www.lelo.com\/blog\/tag\/holidays\/","name":"Holidays Archives - Volont\u00e9","isPartOf":{"@id":"https:\/\/www.lelo.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.lelo.com\/blog\/tag\/holidays\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lelo.com\/blog\/tag\/holidays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Volonte","item":"https:\/\/www.lelo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Holidays"}]},{"@type":"WebSite","@id":"https:\/\/www.lelo.com\/blog\/#website","url":"https:\/\/www.lelo.com\/blog\/","name":"Volont\u00e9","description":"A Sexual Pleasure Blog by LELO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lelo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.lelo.com\/blog\/wp-json\/wp\/v2\/tags\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lelo.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lelo.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lelo.com\/blog\/wp-json\/wp\/v2\/posts?tags=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}